{"id":6257,"date":"2022-03-22T20:25:00","date_gmt":"2022-03-22T19:25:00","guid":{"rendered":"https:\/\/inmobres.es\/?p=6257"},"modified":"2023-03-07T17:54:17","modified_gmt":"2023-03-07T16:54:17","slug":"hermosa-casa-con-apartamento-para-invitados-en-calpe","status":"publish","type":"post","link":"https:\/\/inmobres.es\/fr\/hermosa-casa-con-apartamento-para-invitados-en-calpe\/","title":{"rendered":"Hermosa casa con apartamento para invitados en Calpe"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/inmobres.es\/fr\/hermosa-casa-con-apartamento-para-invitados-en-calpe\/#Precio\" >Precio<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/inmobres.es\/fr\/hermosa-casa-con-apartamento-para-invitados-en-calpe\/#Detalles\" >Detalles<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/inmobres.es\/fr\/hermosa-casa-con-apartamento-para-invitados-en-calpe\/#Caracterisiticas\" >Caracter\u00edsiticas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/inmobres.es\/fr\/hermosa-casa-con-apartamento-para-invitados-en-calpe\/#Descripcion_de_la_hermosa_casa_con_apartamento_para_invitados_en_Calpe\" >Descripci\u00f3n de la hermosa casa con apartamento para invitados en Calpe<\/a><\/li><\/ul><\/nav><\/div>\n\n<p class=\"wp-block-paragraph\">Esta hermosa casa con apartamento para invitados en Calpe, se encuentra en la zona muy solicitada, la urbanizaci\u00f3n Buenavista a tan solo 1km de calas preciosas como \u00ab\u00a0Cala Baladrar\u00a0\u00bb y a 2km de Calpe con todas las comodidades.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Precio\"><\/span>Precio<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Con un precio de\u00a0<strong>690.000\u20ac<\/strong>\u00a0disfruta de las magn\u00edficas temperaturas que nos ofrece Calpe durante todo el a\u00f1o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Detalles\"><\/span>Detalles<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li><strong>Zona:&nbsp;<\/strong>buenavista<\/li>\n\n\n\n<li><strong>Habitaciones:&nbsp;<\/strong>4<\/li>\n\n\n\n<li><strong>Superficie \u00datil:&nbsp;<\/strong>289 m\u00b2<\/li>\n\n\n\n<li><strong>Superficie Parcela:&nbsp;<\/strong>875 m\u00b2<\/li>\n\n\n\n<li><strong>A\u00f1o construcci\u00f3n:<\/strong> 2016<\/li>\n\n\n\n<li><strong>Orientaci\u00f3n:<\/strong> Suroeste<\/li>\n\n\n\n<li><strong>Vistas: <\/strong>A la monta\u00f1a<\/li>\n\n\n\n<li><strong>Refeencia:&nbsp;<\/strong>0339bres<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08344.jpg\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08344.jpg\" alt=\"Sal\u00f3n \/ Comedor\" class=\"wp-image-6262\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08344.jpg 1200w, https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08344-980x653.jpg 980w, https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08344-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Sal\u00f3n \/ Comedor<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Caracterisiticas\"><\/span>Caracter\u00edsiticas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08347.jpg\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08347.jpg\" alt=\"Cocina independiente totalmente equipada\" class=\"wp-image-6261\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08347.jpg 1200w, https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08347-980x653.jpg 980w, https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08347-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Cocina independiente totalmente equipada<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li><strong>Cocina:&nbsp;<\/strong>Independiente &#8211; 16m\u00b2 &#8211; Equipada<\/li>\n\n\n\n<li><strong>Terraza:&nbsp;<\/strong>No Acristalada<\/li>\n\n\n\n<li><strong>Piscina:&nbsp;<\/strong>Privada<\/li>\n\n\n\n<li><strong>Tipo de calefacci\u00f3n:&nbsp;<\/strong>A gas &#8211; Central<\/li>\n\n\n\n<li><strong>Calentador de agua:&nbsp;<\/strong>Gas butano &#8211; Individual<\/li>\n\n\n\n<li><strong>Jard\u00edn:&nbsp;<\/strong>Privado<\/li>\n\n\n\n<li><strong>Garaje:&nbsp;<\/strong>Privado<\/li>\n\n\n\n<li><strong>Ventanas:&nbsp;<\/strong>Aluminio<\/li>\n\n\n\n<li><strong>Suelo del inmueble:&nbsp;<\/strong>Gres<\/li>\n\n\n\n<li><strong>Parking<\/strong>, <strong>Semi-Amueblado<\/strong>, <strong>Puerta Blindada<\/strong>, <strong>Aire Acondicionado<\/strong>, <strong>Armarios empotrados<\/strong>, <strong>Doble acristalamiento:&nbsp;<\/strong>Si<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Descripcion_de_la_hermosa_casa_con_apartamento_para_invitados_en_Calpe\"><\/span>Descripci\u00f3n de la hermosa casa con apartamento para invitados en Calpe<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esta hermosa y gran casa familiar se encuentra a poca distancia de restaurantes, supermercados, servicio de autob\u00fas y playas (a unos 2 km de distancia).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La casa est\u00e1 construida a un nivel muy alto y est\u00e1 en perfectas condiciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la parte principal de la casa encontramos un sal\u00f3n comedor muy atractivo, amplio y luminoso que conduce a una gran terraza cubierta con vistas a la piscina de 5 x 9, una cocina grande y moderna en perfecto estado, 3 dormitorios (el principal con ba\u00f1o y vestidor), un ba\u00f1o familiar. Un amplio garaje con lavadero con acceso directo a la vivienda. Calefacci\u00f3n central de gas y aire acondicionado en toda la casa principal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El apartamento de invitados est\u00e1 arriba (al que se accede a trav\u00e9s de una escalera privada) y consta de sal\u00f3n\/comedor\/cocina, dormitorio doble, ba\u00f1o y una azotea muy grande.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08353.jpg\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08353.jpg\" alt=\"Dormitorio\" class=\"wp-image-6260\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08353.jpg 1200w, https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08353-980x653.jpg 980w, https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08353-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Dormitorio<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08369.jpg\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08369.jpg\" alt=\"Vistas de la hermosa casa con apartamento para invitados en Calpe\" class=\"wp-image-6259\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08369.jpg 1200w, https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08369-980x653.jpg 980w, https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/inmobres-dsc08369-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Vistas de la hermosa casa con apartamento para invitados en Calpe<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Las ventanas de aluminio tienen mosquiteras, las puertas de entrada a la parcela y al garaje son autom\u00e1ticas y la propiedad tiene orientaci\u00f3n suroeste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuenta una alarma de seguridad. La zona ajardinada tiene algo de c\u00e9sped artificial, \u00e1rboles frutales y la zona de la piscina y es de f\u00e1cil mantenimiento. Podr\u00eda haber espacio para una autocaravana si es necesario.<br>Esta propiedad se encuentra en una ubicaci\u00f3n soleada perfecta y ser\u00eda un hogar maravilloso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfNo es la propiedad que buscas? En nuestra secci\u00f3n de&nbsp;<a href=\"https:\/\/inmobres.es\/categorias\/promociones\/\">Promociones<\/a>&nbsp;encontrar\u00e1s muchas m\u00e1s ofertas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"tel:+34656633190\" target=\"_blank\" rel=\"noreferrer noopener\">Ll\u00e1manos<\/a>&nbsp;para una visita o solicita&nbsp;<a href=\"mailto:info@inmobres.com\">m\u00e1s informaci\u00f3n por correo electr\u00f3nico<\/a>. Tambi\u00e9n puedes ver m\u00e1s fotos de esta propiedad visitando&nbsp;<a href=\"https:\/\/www.inmobres.com\/es\/casa-chalet--calpe-calp-buenavista-con--es833688.html\" rel=\"noopener\">nuestra p\u00e1gina web<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta hermosa casa con apartamento para invitados en Calpe, se encuentra en la urb. Buenavista a tan solo 1km de calas como \u00ab\u00a0Cala Baladrar\u00a0\u00bb y a 2km de Calpe con todas las comodidades.<\/p>\n","protected":false},"author":3,"featured_media":6258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[543],"tags":[29,32,67,53,14,9,22,328,92],"class_list":["post-6257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-calp","tag-calpe","tag-chalet","tag-costa-blanca","tag-inmobiliaria","tag-inmobres","tag-oferta","tag-piscina-privada","tag-villa"],"_links":{"self":[{"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/posts\/6257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/comments?post=6257"}],"version-history":[{"count":3,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/posts\/6257\/revisions"}],"predecessor-version":[{"id":10643,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/posts\/6257\/revisions\/10643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/media\/6258"}],"wp:attachment":[{"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/media?parent=6257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/categories?post=6257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/tags?post=6257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}