{"id":6168,"date":"2021-11-17T20:20:00","date_gmt":"2021-11-17T19:20:00","guid":{"rendered":"https:\/\/inmobres.es\/?p=6168"},"modified":"2023-03-07T17:53:28","modified_gmt":"2023-03-07T16:53:28","slug":"amplia-villa-de-4-dormitorios-y-piscina-en-calpe","status":"publish","type":"post","link":"https:\/\/inmobres.es\/fr\/amplia-villa-de-4-dormitorios-y-piscina-en-calpe\/","title":{"rendered":"Amplia villa de 4 dormitorios y piscina en Calpe"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/inmobres.es\/fr\/amplia-villa-de-4-dormitorios-y-piscina-en-calpe\/#%C2%A1VENDIDO\" >\u00a1VENDIDO!<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/inmobres.es\/fr\/amplia-villa-de-4-dormitorios-y-piscina-en-calpe\/#Precio\" >Precio<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/inmobres.es\/fr\/amplia-villa-de-4-dormitorios-y-piscina-en-calpe\/#Detalles\" >Detalles<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/inmobres.es\/fr\/amplia-villa-de-4-dormitorios-y-piscina-en-calpe\/#Caracteristicas\" >Caracter\u00edsticas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/inmobres.es\/fr\/amplia-villa-de-4-dormitorios-y-piscina-en-calpe\/#Descripcion_de_la_amplia_villa_de_4_dormitorios_y_piscina_en_Calpe\" >Descripci\u00f3n de la amplia villa de 4 dormitorios y piscina en Calpe<\/a><\/li><\/ul><\/nav><\/div>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%A1VENDIDO\"><\/span><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">\u00a1VENDIDO!<\/mark><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esta amplia villa de 4 dormitorios y piscina en Calpe se encuentra en una urbanizaci\u00f3n muy tranquila, La Empedrola. A pocos minutos en coche de sus playas de arena fina y aguas cristalinas con bandera azul y de todas las comodidades.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"precio\"><span class=\"ez-toc-section\" id=\"Precio\"><\/span>Precio<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Por un precio de&nbsp;<strong>450.000\u20ac<\/strong>&nbsp;disfruta durante todo el a\u00f1o de las magn\u00edficas temperaturas que nos ofrece la Costa Blanca.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"detalles\"><span class=\"ez-toc-section\" id=\"Detalles\"><\/span>Detalles<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li><strong>Tipo de propiedad:&nbsp;<\/strong>Casa \/ Chalet<\/li>\n\n\n\n<li><strong>Poblaci\u00f3n:&nbsp;<\/strong>Calpe \/ Calp<\/li>\n\n\n\n<li><strong>Zona:&nbsp;<\/strong>Empedrola<\/li>\n\n\n\n<li><strong>Habitaciones:&nbsp;<\/strong>4<\/li>\n\n\n\n<li><strong>Ba\u00f1os:&nbsp;<\/strong>3<\/li>\n\n\n\n<li><strong>Superficie \u00datil:&nbsp;<\/strong>171 m\u00b2<\/li>\n\n\n\n<li><strong>Superficie Parcela:&nbsp;<\/strong>1034 m\u00b2<\/li>\n\n\n\n<li><strong>Orientaci\u00f3n:&nbsp;<\/strong>Suroeste<\/li>\n\n\n\n<li><strong>Referencia:&nbsp;<\/strong>0325bres<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07833.jpg\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07833.jpg\" alt=\"Sal\u00f3n \/ Comedor\" class=\"wp-image-6171\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07833.jpg 1200w, https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07833-980x653.jpg 980w, https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07833-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Sal\u00f3n \/ Comedor<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"caracteristicas\"><span class=\"ez-toc-section\" id=\"Caracteristicas\"><\/span>Caracter\u00edsticas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07832.jpg\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07832.jpg\" alt=\"Cocina\" class=\"wp-image-6172\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07832.jpg 1200w, https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07832-980x653.jpg 980w, https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07832-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Cocina<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li><strong>Cocina:&nbsp;<\/strong>Independiente &#8211; Reformada &#8211; Equipada<\/li>\n\n\n\n<li><strong>Terraza:&nbsp;<\/strong>Acristalada<\/li>\n\n\n\n<li><strong>Vistas:&nbsp;<\/strong>A la monta\u00f1a<\/li>\n\n\n\n<li><strong>Piscina:&nbsp;<\/strong>Privada<\/li>\n\n\n\n<li><strong>Tipo de calefacci\u00f3n:&nbsp;<\/strong>Gasoil &#8211; Central<\/li>\n\n\n\n<li><strong>Suelo del inmueble:&nbsp;<\/strong>Gres<\/li>\n\n\n\n<li><strong>Semi-Amueblado, Reformado, Trastero, Aire Acondicionado, Chimenea, Armarios Empotrados, Doble Acristalamiento, Parking:&nbsp;<\/strong>Si<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"descripcion-de-la-amplia-villa-de-4-dormitorios-y-piscina-en-calpe\"><span class=\"ez-toc-section\" id=\"Descripcion_de_la_amplia_villa_de_4_dormitorios_y_piscina_en_Calpe\"><\/span>Descripci\u00f3n de la amplia villa de 4 dormitorios y piscina en Calpe<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esta hermosa casa familiar tiene sol todo el d\u00eda, y se pone sobre la ladera de la monta\u00f1a donde ver\u00e1 maravillosas puestas de sol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La propiedad fue construida en 1987 y ha sido cuidada con cari\u00f1o por sus due\u00f1os. La villa se encuentra en una parcela llana y tiene un gran jard\u00edn natural maravilloso con muchas \u00e1reas para sentarse. El \u00e1rea de la piscina es privada y tiene unas maravillosas vistas a la monta\u00f1a, ideales para relajarse y disfrutar del sol del mediterraneo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La planta principal consta de un gran sal\u00f3n para tomar el sol que a su vez conduce a un atractivo sal\u00f3n con estufa de le\u00f1a y comedor. De aqu\u00ed pasamos a los tres dormitorios y dos ba\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la terraza acristalada hay una escalera que baja al \u00e1rea de invitados de 1 dormitorio grande, 1 ba\u00f1o, sal\u00f3n y cocina peque\u00f1a. El sal\u00f3n era originalmente un garaje que se convirti\u00f3 profesionalmente, y si est\u00e1 en su lista de deseos, se podr\u00eda volver a convertir f\u00e1cilmente, todav\u00eda dejando espacio debajo para sus invitados y familiares. Hay una cochera cubierta en el jard\u00edn que tambi\u00e9n podr\u00eda convertirse en un garaje.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07841.jpg\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07841.jpg\" alt=\"Dormitorio de la amplia villa de 4 dormitorios y piscina en Calpe\" class=\"wp-image-6170\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07841.jpg 1200w, https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07841-980x653.jpg 980w, https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07841-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Dormitorio de la amplia villa de 4 dormitorios y piscina en Calpe<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07840.jpg\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07840.jpg\" alt=\"Ba\u00f1o con ba\u00f1era\" class=\"wp-image-6173\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07840.jpg 1200w, https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07840-980x653.jpg 980w, https:\/\/inmobres.es\/wp-content\/uploads\/2021\/11\/inmobres-dsc07840-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Ba\u00f1o con ba\u00f1era<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Toda la villa tiene ventanas de doble acristalamiento y la mayor\u00eda con persianas. Hay calefacci\u00f3n central de gasoil, aire acondicionado, internet de fibra (wifi), tel\u00e9fono fijo y sistema de alarma de timbre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La piscina tiene una bomba de calor para que pueda utilizar la piscina durante un per\u00edodo prolongado del a\u00f1o.<br>Se vende parcialmente amueblado, esta podr\u00eda ser su vivienda ideal.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfNo es la propiedad que buscas? En nuestra secci\u00f3n de&nbsp;<a href=\"https:\/\/inmobres.es\/categorias\/promociones\/\">Promociones<\/a>&nbsp;encontrar\u00e1s muchas m\u00e1s ofertas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"tel:+34656633190\" target=\"_blank\">Ll\u00e1manos<\/a>&nbsp;para una visita o solicita&nbsp;<a href=\"mailto:info@inmobres.com\">m\u00e1s informaci\u00f3n por correo electr\u00f3nico<\/a>. Tambi\u00e9n puedes ver m\u00e1s fotos de esta propiedad visitando&nbsp;<a href=\"https:\/\/www.inmobres.com\/es\/casa-chalet--calpe-calp-empedrola-con--es809049.html\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.inmobres.com\/es\/casa-chalet--calpe-calp-empedrola-con--es809049.html\" rel=\"noreferrer noopener\">nuestra p\u00e1gina web<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta amplia villa de 4 dormitorios y piscina privada en Calpe se encuentra en una la urbanizaci\u00f3n La Empedrola. A pocos minutos en coche de sus playas de bandera azul y todas las comodidades.<\/p>\n","protected":false},"author":3,"featured_media":6169,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[543],"tags":[29,32,67,53,14,9,92],"class_list":["post-6168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-calp","tag-calpe","tag-chalet","tag-costa-blanca","tag-inmobiliaria","tag-inmobres","tag-villa"],"_links":{"self":[{"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/posts\/6168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/comments?post=6168"}],"version-history":[{"count":2,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/posts\/6168\/revisions"}],"predecessor-version":[{"id":10642,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/posts\/6168\/revisions\/10642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/media\/6169"}],"wp:attachment":[{"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/media?parent=6168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/categories?post=6168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/tags?post=6168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}