{"id":10186,"date":"2023-02-07T13:30:00","date_gmt":"2023-02-07T12:30:00","guid":{"rendered":"https:\/\/inmobres.es\/?p=10186"},"modified":"2023-02-16T10:58:33","modified_gmt":"2023-02-16T09:58:33","slug":"programacion-de-mig-any-2023-en-altea","status":"publish","type":"post","link":"https:\/\/inmobres.es\/fr\/programacion-de-mig-any-2023-en-altea\/","title":{"rendered":"Programaci\u00f3n de Mig Any 2023 en Altea"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/inmobres.es\/fr\/programacion-de-mig-any-2023-en-altea\/#Programacion_de_Mig_Any_2023_en_Altea\" >Programaci\u00f3n de Mig Any 2023 en Altea.<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/inmobres.es\/fr\/programacion-de-mig-any-2023-en-altea\/#Viernes_10\" >Viernes 10<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/inmobres.es\/fr\/programacion-de-mig-any-2023-en-altea\/#Sabado_11\" >S\u00e1bado 11<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/inmobres.es\/fr\/programacion-de-mig-any-2023-en-altea\/#Domingo_12\" >Domingo 12<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/inmobres.es\/fr\/programacion-de-mig-any-2023-en-altea\/#Sabado_18\" >S\u00e1bado 18<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<p class=\"wp-block-paragraph\">Inmobres te trae la programaci\u00f3n de Mig Any 2023 en Altea. Consulta los actos y fiestas que se celebrar\u00e1n del 10 al 18 de febrero.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Programacion_de_Mig_Any_2023_en_Altea\"><\/span>Programaci\u00f3n de Mig Any 2023 en Altea.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Viernes_10\"><\/span>Viernes 10<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>20.00h<\/strong> Palau Altea, nombramiento de Cargos Festeros 2023. Entrada libre limitada al aforo.<br><strong>23.00h<\/strong> Carpa Festera Baile de Cargos Bandeta \u201cL\u2019aureba\u201d y Dj. Parking Basseta Centro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Sabado_11\"><\/span>S\u00e1bado 11<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>11.00h<\/strong> Club del Festeret. Carpa festera&nbsp; Juegos, hinchables, manualidades. con la colaboraci\u00f3n de Projectes Educatius.<br><strong>17.15h<\/strong> Romer\u00eda Sant Blai. Concentraci\u00f3n de la Filaes, Cargo sFesteros y Autoridades en la Plaza del Ayuntamiento y Romeria de San Blas, ofrenda de rollos. Misa Solemne en honor del Patr\u00f3n de Altea y de la Fiesta de Moros y Cristianos, San Blas. Preside Don Francisco Morat\u00f3 Boronat. P\u00e1rroco de Altea y Asesor Religioso del \u00c1rea V de Undef. Cantada por la Coral de la Sociedad Filarm\u00f3nica Alteanense. Bendici\u00f3n y reparto de los rollos de San Blas. Acabada la Misa, pasacalles hasta la Plaza del Ayuntamiento.<br><strong>23.00h<\/strong> Carpa Festera \u2013 Baile de Cargos. Bandeta \u201cToca\u2019t un ou\u201d y Dj. Parking Basseta-Centro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Domingo_12\"><\/span>Domingo 12<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>08.00 a 09.00h<\/strong> Acampada de los festeros, almuerzo de las Filaes en el&nbsp;aparcamiento Basseta\/Centro.<br><strong>11.45h<\/strong>&nbsp;Concentraci\u00f3n de todos los festeros y festeras infantiles, Cargos Festeros, Bandas de M\u00fasica, Banderas de la Files frente al Mercado y empezar la Entrada infantil 2023.<br><strong>12.00h<\/strong>&nbsp;Entrada Infantil. Itinerario: Av. Jaume I hasta la Plaza del Ayuntamiento,&nbsp;hasta el parking Basseta\/Centro.&nbsp;Seguidamente, comida de las Filaes.<br><strong>16.15h<\/strong>&nbsp;Concentraci\u00f3n en la Plaza del Lavador de las filaes, Bandas de&nbsp;M\u00fasica, Cargos y banderas. Acto de&nbsp;Tomada de Banderas\u201d Itinerario de&nbsp;costumbre; depositando las banderas en&nbsp;el Museo Festero y saludo de los Cargos&nbsp;Festeros. Interpretaci\u00f3n del himno de&nbsp;la Fiesta \u201cIda y Vuelta\u201d. Seguidamente,&nbsp;chocolatada para las Filaes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Sabado_18\"><\/span>S\u00e1bado 18<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>17.00h<\/strong>&nbsp;XIV Certamen de M\u00fasica Festera organizado por la Sociedad Recreativa Musical de Altea la Vella. Centro Cultural de Altea la Vella. Previamente, pasacalles con las bandas participantes. acompa\u00f1adas por la Junta y Cargos de&nbsp;la Federaci\u00f3n y Autoridades.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2023\/02\/Inmobres-mig_any_altea_2023_caraA.jpg\"><img decoding=\"async\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2023\/02\/Inmobres-mig_any_altea_2023_caraA.jpg\" alt=\"Portada programaci\u00f3n\" class=\"wp-image-10187\" width=\"696\" height=\"476\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2023\/02\/Inmobres-mig_any_altea_2023_caraA.jpg 696w, https:\/\/inmobres.es\/wp-content\/uploads\/2023\/02\/Inmobres-mig_any_altea_2023_caraA-480x329.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 696px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Portada programaci\u00f3n<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2023\/02\/Inmobres-mig_any_altea_2023_caraB-768x526-1.jpg\"><img decoding=\"async\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2023\/02\/Inmobres-mig_any_altea_2023_caraB-768x526-1.jpg\" alt=\"Programaci\u00f3n de Mig Any 2023 en Altea.\" class=\"wp-image-10191\" width=\"593\" height=\"406\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2023\/02\/Inmobres-mig_any_altea_2023_caraB-768x526-1.jpg 593w, https:\/\/inmobres.es\/wp-content\/uploads\/2023\/02\/Inmobres-mig_any_altea_2023_caraB-768x526-1-480x329.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 593px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Programaci\u00f3n de Mig Any 2023 en Altea.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En&nbsp;<strong>Inmobres te ayuda a encontrar la casa de tus sue\u00f1os, junto al Mediterr\u00e1neo.<\/strong><br>Disfruta todos los a\u00f1os de la fiesta de&nbsp;<strong>Moros y Cristianos de Altea&nbsp;<\/strong>y el resto de fiestas de la Costa Blanca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"tel:+34656633190\" target=\"_blank\">Ll\u00e1manos<\/a>&nbsp; o escribenos un&nbsp;<a href=\"mailto:info@inmobres.com\">correo electr\u00f3nico<\/a>. Tambi\u00e9n puedes venir a vernos a&nbsp;<a href=\"https:\/\/g.page\/InmobresCalpe?share\" target=\"_blank\" rel=\"noreferrer noopener\">nuestra oficina<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inmobres te trae la programaci\u00f3n de Mig Any 2023 en Altea. Consulta los actos y fiestas que se celebrar\u00e1n del 10 al 18 de febrero.<\/p>\n","protected":false},"author":3,"featured_media":10195,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[18],"tags":[62,29,32,53,41,14,9,828,79],"class_list":["post-10186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-y-fiestas","tag-altea","tag-calp","tag-calpe","tag-costa-blanca","tag-fiesta","tag-inmobiliaria","tag-inmobres","tag-mig-any-2023","tag-programacion"],"_links":{"self":[{"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/posts\/10186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/comments?post=10186"}],"version-history":[{"count":2,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/posts\/10186\/revisions"}],"predecessor-version":[{"id":10381,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/posts\/10186\/revisions\/10381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/media\/10195"}],"wp:attachment":[{"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/media?parent=10186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/categories?post=10186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inmobres.es\/fr\/wp-json\/wp\/v2\/tags?post=10186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}