{"id":3805,"date":"2019-06-12T12:30:35","date_gmt":"2019-06-12T10:30:35","guid":{"rendered":"https:\/\/inmobres.es\/?p=3805"},"modified":"2023-03-07T18:04:39","modified_gmt":"2023-03-07T17:04:39","slug":"hermosa-villa-de-4-habitaciones-y-piscina-privada","status":"publish","type":"post","link":"https:\/\/inmobres.es\/en\/hermosa-villa-de-4-habitaciones-y-piscina-privada\/","title":{"rendered":"Hermosa Villa de 4 habitaciones y piscina privada"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/inmobres.es\/en\/hermosa-villa-de-4-habitaciones-y-piscina-privada\/#%C2%A1VENDIDO\" >\u00a1VENDIDO!<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/inmobres.es\/en\/hermosa-villa-de-4-habitaciones-y-piscina-privada\/#Precio_de_la_Hermosa_Villa\" >Precio de la Hermosa Villa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/inmobres.es\/en\/hermosa-villa-de-4-habitaciones-y-piscina-privada\/#Detalles\" >Detalles<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/inmobres.es\/en\/hermosa-villa-de-4-habitaciones-y-piscina-privada\/#Caracteristicas\" >Caracter\u00edsticas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/inmobres.es\/en\/hermosa-villa-de-4-habitaciones-y-piscina-privada\/#Descripcion\" >Descripci\u00f3n<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;2px||7px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%A1VENDIDO\"><\/span><span style=\"color: #e02b20;\"><strong>\u00a1VENDIDO!<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Hermosa Villa de 4 habitaciones y piscina privada. Orientada al sur y ubicada en una tranquila zona verde de Calpe.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;3px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Precio_de_la_Hermosa_Villa\"><\/span><strong>Precio de la Hermosa Villa<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-size: large\"><strong>Antes\u00a0<\/strong><span style=\"text-decoration: line-through\">670.000 \u20ac<\/span> (-26%)<\/span><\/p>\n<p><span style=\"font-size: large\"><strong>Ahora<\/strong> 495.000 \u20ac<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Detalles\"><\/span><strong>Detalles<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><strong>Poblaci\u00f3n:\u00a0<\/strong>Calpe \/ Calp<\/li>\n<li><strong>Habitaciones:\u00a0<\/strong>4<\/li>\n<li><strong>Ba\u00f1os:\u00a0<\/strong>3<\/li>\n<li><strong> \u00datil:\u00a0<\/strong>258 m\u00b2<\/li>\n<li><strong> Construida:\u00a0<\/strong>258 m\u00b2<\/li>\n<li><strong> Parcela:\u00a0<\/strong>2500\u00a0m\u00b2<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;]<div id=\"attachment_3816\" style=\"width: 1009px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3816\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2019\/06\/Inmobres-04-157_11521565454.jpg\" width=\"999\" height=\"667\" alt=\"\" class=\"wp-image-3816 size-full\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2019\/06\/Inmobres-04-157_11521565454.jpg 999w, https:\/\/inmobres.es\/wp-content\/uploads\/2019\/06\/Inmobres-04-157_11521565454-300x200.jpg 300w, https:\/\/inmobres.es\/wp-content\/uploads\/2019\/06\/Inmobres-04-157_11521565454-768x513.jpg 768w, https:\/\/inmobres.es\/wp-content\/uploads\/2019\/06\/Inmobres-04-157_11521565454-610x407.jpg 610w, https:\/\/inmobres.es\/wp-content\/uploads\/2019\/06\/Inmobres-04-157_11521565454-560x374.jpg 560w\" sizes=\"(max-width: 999px) 100vw, 999px\" \/><p id=\"caption-attachment-3816\" class=\"wp-caption-text\">habitaci\u00f3n de la hermosa villa<\/p><\/div>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;]<div id=\"attachment_3820\" style=\"width: 1009px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3820\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2019\/06\/Inmobres-03-1739_11521565428-1.jpg\" width=\"999\" height=\"667\" alt=\"\" class=\"wp-image-3820 size-full\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2019\/06\/Inmobres-03-1739_11521565428-1.jpg 999w, https:\/\/inmobres.es\/wp-content\/uploads\/2019\/06\/Inmobres-03-1739_11521565428-1-300x200.jpg 300w, https:\/\/inmobres.es\/wp-content\/uploads\/2019\/06\/Inmobres-03-1739_11521565428-1-768x513.jpg 768w, https:\/\/inmobres.es\/wp-content\/uploads\/2019\/06\/Inmobres-03-1739_11521565428-1-610x407.jpg 610w, https:\/\/inmobres.es\/wp-content\/uploads\/2019\/06\/Inmobres-03-1739_11521565428-1-560x374.jpg 560w\" sizes=\"(max-width: 999px) 100vw, 999px\" \/><p id=\"caption-attachment-3820\" class=\"wp-caption-text\">cocina<\/p><\/div>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Caracteristicas\"><\/span><strong>Caracter\u00edsticas<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><strong>A\u00f1o Construcci\u00f3n:\u00a0<\/strong>2005<\/li>\n<li><strong>Cocina:\u00a0<\/strong>Independiente<\/li>\n<li><strong>Terraza:\u00a0<\/strong>No Acristalada<\/li>\n<li><strong>Orientaci\u00f3n:\u00a0<\/strong>Sur<\/li>\n<li><strong>Vistas:\u00a0<\/strong>A la monta\u00f1a<\/li>\n<li><strong>Piscina:\u00a0<\/strong>Privada<\/li>\n<li><strong>Tipo de calefacci\u00f3n:\u00a0<\/strong>A gas &#8211; Central<\/li>\n<li><strong>Calentador de agua:\u00a0<\/strong>&#8211; Central<\/li>\n<li><strong>Jard\u00edn:\u00a0<\/strong>Privado<\/li>\n<li><strong>Parking,\u00a0<\/strong><strong>Amueblado,\u00a0<\/strong><strong>Trastero,\u00a0<\/strong><strong>Aire Acondicionado,\u00a0<\/strong><strong>Chimenea,\u00a0<\/strong><strong>S\u00f3tano,\u00a0<\/strong><strong>Armarios empotrados,\u00a0<\/strong><strong>Doble acristalamiento<\/strong><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;13px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Descripcion\"><\/span><strong>Descripci\u00f3n<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Hermosa Villa orientada al sur, construida a finales de 2005 y a\u00fan en perfectas condiciones, ubicado en una tranquila zona verde de Calpe. Las vistas de la monta\u00f1a son impresionantes y sol todo el d\u00eda, hasta el atardecer. En el nivel principal, encontramos un gran sal\u00f3n\/comedor con chimenea, cocina, 2 dormitorios y dos ba\u00f1os. Una gran terraza cubierta con vistas a la piscina y zona de barbacoa.<br \/>El apartamento de invitados consta de 2 dormitorios, 1, sal\u00f3n, cocina, lavadero y terraza abierta que desemboca en un bonito Jard\u00edn andaluz, organizado en estilo tropical con un bosque de pinos a un lado.<\/p>\n<p>Todas las comodidades modernas de esta encantadora Villa incluyen: calefacci\u00f3n central de gas, aire acondicionado, tel\u00e9fono\/Internet, alarma, sistema de riego autom\u00e1tico, doble acristalamiento, persianas en todas la ventanas y espacio de estacionamiento cubierto que f\u00e1cilmente podr\u00eda convertirse en un garaje cerrado. Aparte del garaje dispone de un amplio espacio de estacionamiento y puerta de entrada autom\u00e1tica para coche. Junto al motor de la piscina, tiene una grand\u00edsima zona de almacenamiento.\u00a0<strong>Esta casa tiene de todo lo que puedas necesitar y est\u00e1 a s\u00f3lo 4 kms. del pueblo de Calpe. Paz y tranquilidad, pero a poca distancia de la ciudad y las playas.<\/strong><br \/>Para mas informaci\u00f3n sobre esta propiedad, cons\u00faltenos.<\/p>\n<p>Puedes ver m\u00e1s fotos en <a href=\"https:\/\/www.inmobres.com\/es\/casa-chalet-en-calpe-calp-calpe-con-piscina-es404027.html\" target=\"_blank\" rel=\"noopener noreferrer\">Inmobres<\/a>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosa Villa de 4 habitaciones y piscina privada. Orientada al sur, ubicada en una zona tranquila de Calpe y con vistas impresionantes a la monta\u00f1a<\/p>\n","protected":false},"author":3,"featured_media":3842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[543],"tags":[32,53,9,22,92],"class_list":["post-3805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-calpe","tag-costa-blanca","tag-inmobres","tag-oferta","tag-villa"],"_links":{"self":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts\/3805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/comments?post=3805"}],"version-history":[{"count":2,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts\/3805\/revisions"}],"predecessor-version":[{"id":10657,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts\/3805\/revisions\/10657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/media\/3842"}],"wp:attachment":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/media?parent=3805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/categories?post=3805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/tags?post=3805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}