{"id":3773,"date":"2019-06-05T12:30:09","date_gmt":"2019-06-05T10:30:09","guid":{"rendered":"https:\/\/inmobres.es\/?p=3773"},"modified":"2019-05-29T12:06:41","modified_gmt":"2019-05-29T10:06:41","slug":"moros-y-cristianos-moraira-2019","status":"publish","type":"post","link":"https:\/\/inmobres.es\/en\/moros-y-cristianos-moraira-2019\/","title":{"rendered":"Moros y Cristianos 2019 en Moraira"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/inmobres.es\/en\/moros-y-cristianos-moraira-2019\/#Programacion\" >Programaci\u00f3n<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/inmobres.es\/en\/moros-y-cristianos-moraira-2019\/#Viernes_7\" >Viernes 7\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/inmobres.es\/en\/moros-y-cristianos-moraira-2019\/#Sabado_8\" >S\u00e1bado 8<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/inmobres.es\/en\/moros-y-cristianos-moraira-2019\/#Domingo_9\" >Domingo 9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/inmobres.es\/en\/moros-y-cristianos-moraira-2019\/#Lunes_10\" >Lunes 10<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/inmobres.es\/en\/moros-y-cristianos-moraira-2019\/#Jueves_13\" >Jueves 13<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/inmobres.es\/en\/moros-y-cristianos-moraira-2019\/#Viernes_14\" >Viernes 14<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/inmobres.es\/en\/moros-y-cristianos-moraira-2019\/#Sabado_15\" >S\u00e1bado 15<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/inmobres.es\/en\/moros-y-cristianos-moraira-2019\/#Domingo_16\" >Domingo 16<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.23.3&#8243;][et_pb_row custom_padding=&#8221;||12px|||&#8221; _builder_version=&#8221;3.23.3&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.23.3&#8243;][et_pb_text _builder_version=&#8221;3.23.3&#8243;]<\/p>\n<p>No puedes faltar a esta tradicional fiesta de los <strong>Moros y Cristianos<\/strong> que se celebra <strong>del 7 al 16 de Junio 2019 en Moraira.<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding=&#8221;12px||0px|||&#8221; _builder_version=&#8221;3.23.3&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.23.3&#8243;][et_pb_text _builder_version=&#8221;3.23.3&#8243;]<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Programacion\"><\/span><strong>Programaci\u00f3n<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><strong><\/strong><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Viernes_7\"><\/span><span style=\"text-decoration: underline\"><b>Viernes 7\u00a0<\/b><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><b>19.30h\u00a0<\/b>Inauguraci\u00f3n Mercado Medieval Andalus\u00ed.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Sabado_8\"><\/span><span style=\"text-decoration: underline\"><strong>S\u00e1bado 8<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>12.00h<\/strong> Concentraci\u00f3n de moros y cristianos en el Bosque Urbano, preparaci\u00f3n de la Comida de Hermandad y juegos infantiles. Todo amenizado por la charanga &#8220;Batacl\u00e1n&#8221; de Jal\u00f3n.<\/p>\n<p><strong>21.30h<\/strong> Concentraci\u00f3n de todas las fil\u00e1s en el Fort\u00ed y pasacalle acompa\u00f1ados por la Colla &#8220;El Falc\u00f3&#8221; de Teulada y la Colla &#8220;la Llebetj\u00e0&#8221; del Poble Nou hasta la explanada del castillo.<\/p>\n<p><strong>22.00h<\/strong> Acto de Presentaci\u00f3n de Banderines en la explanada del Castillo. Al finalizar verbena, con la actuaci\u00f3n del trio &#8220;Ibiza&#8221;.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Domingo_9\"><\/span><span style=\"text-decoration: underline\"><strong>Domingo 9<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>18.00h<\/strong> Gran Festival Internacional de M\u00fasica Jazz, Folk, Rock y Country.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Lunes_10\"><\/span><span style=\"text-decoration: underline\"><strong>Lunes 10<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>20.00h<\/strong> Concierto de la Coral Brit\u00e1nica en la Parroquia de Moraira.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding=&#8221;10px||29px|||&#8221; _builder_version=&#8221;3.23.3&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.23.3&#8243;][et_pb_text _builder_version=&#8221;3.23.3&#8243;]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Jueves_13\"><\/span><span style=\"text-decoration: underline\"><strong>Jueves 13<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>20.00h<\/strong> Preg\u00f3n de Fiestas a cargo de Don Manuel Bru Llobell y entrega de premios del XXI Concurso de Dibujos organizado por la Junta Central y en colaboraci\u00f3n del AMPA Cap d&#8217;Or (Moraira) y AMPA San Vicente Ferrer\u00a0 (Teulada). A continuaci\u00f3n, Concierto de la Colla el Fal\u00e7\u00f3 de Teulada en la calle Doctor Calatayud.<\/p>\n<p><strong>21.30h<\/strong> Cena de Hermandad en la calle Doctor Calatayud, amenizada por &#8220;El Rull de Pedreguer&#8221;.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Viernes_14\"><\/span><span style=\"text-decoration: underline\"><strong>Viernes 14<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>13.00h<\/strong> Concentraci\u00f3n de todas las fil\u00e1s en el Fort\u00ed y pasacalle informal amenizado por las bandas de m\u00fasica de Jal\u00f3n y Quatretonda.<\/p>\n<p><strong>13.30h<\/strong> Disparo de Arcabucer\u00eda en la explanada del Castillo.<\/p>\n<p><strong>19.30h<\/strong> Ofrenda de Flores en honor al Sant\u00edsimo Cristo de Moraira en la Ermita del Castillo. Al finalizar el acto todas las fil\u00e1s tocar\u00e1n la marcha &#8220;Creu Daur\u00e0&#8221; bajo la direcci\u00f3n de Pau Climent Montaner director de la Agrupaci\u00f3 Musical Cultural de Teulada.\u00a0<\/p>\n<p><strong>23.00h<\/strong> Conquista Mora en la Playa de La Ampolla, seguido de la Embajada Mora y Conquista del Castillo de Moraira. A continuaci\u00f3n noche de capitan\u00edas.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding=&#8221;30px|||||&#8221; custom_margin=&#8221;-44px|auto||auto||&#8221; _builder_version=&#8221;3.23.3&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.23.3&#8243;][et_pb_text _builder_version=&#8221;3.23.3&#8243;]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Sabado_15\"><\/span><span style=\"text-decoration: underline\"><strong>S\u00e1bado 15<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>08.00h<\/strong> Despertada general con arcabuces con la charanga el Batacl\u00e1n de Jal\u00f3n.<\/p>\n<p><strong>11.00h<\/strong> Concentraci\u00f3n de todas las fil\u00e1s en el Fort\u00ed y a continuaci\u00f3n pasacalle.<\/p>\n<p><strong>12.00h<\/strong> Misa en honor al Sant\u00edsimo Cristo en la Parroquia de Moraira.<\/p>\n<p><strong>13.00h<\/strong> Disparo de arcabucer\u00eda en la explanada del Castillo y desfile informal.<\/p>\n<p><strong>20.00h<\/strong> Reconquista Cristiana en la playa de la Ampolla. Asalto al Castillo de Moraira por parte del Bando Cristiano seguido de la Embajada Cristiana y Reconquista del Castillo.<\/p>\n<p><strong>00.00h<\/strong> Retreta Popular desde la explanada del Castillo de Moraira hasta la avenida del Portet. A continuaci\u00f3n noche de c\u00e1bilas con la actuaci\u00f3n de la Orquesta M\u00e1xima en la avenida del Portet.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.23.3&#8243;][et_pb_text _builder_version=&#8221;3.23.3&#8243; custom_margin=&#8221;50px||&#8221;]<div id=\"attachment_3777\" style=\"width: 970px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3777\" class=\"wp-image-3777 size-full\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2019\/05\/moors-1863231_960_720.jpg\" alt=\"\" width=\"960\" height=\"635\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2019\/05\/moors-1863231_960_720.jpg 960w, https:\/\/inmobres.es\/wp-content\/uploads\/2019\/05\/moors-1863231_960_720-300x198.jpg 300w, https:\/\/inmobres.es\/wp-content\/uploads\/2019\/05\/moors-1863231_960_720-768x508.jpg 768w, https:\/\/inmobres.es\/wp-content\/uploads\/2019\/05\/moors-1863231_960_720-610x403.jpg 610w, https:\/\/inmobres.es\/wp-content\/uploads\/2019\/05\/moors-1863231_960_720-560x370.jpg 560w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><p id=\"caption-attachment-3777\" class=\"wp-caption-text\">Moros y cristianos 2019 en Moraira<\/p><\/div><br \/>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding=&#8221;20px||0px|||&#8221; custom_margin=&#8221;-34px|auto||auto||&#8221; _builder_version=&#8221;3.23.3&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.23.3&#8243;][et_pb_text _builder_version=&#8221;3.23.3&#8243;]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Domingo_16\"><\/span><span style=\"text-decoration: underline\"><strong>Domingo 16<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>08.00h<\/strong> Despertada general con arcabuces.<\/p>\n<p><strong>12.00h<\/strong> Pasacalle informal con banderines.<\/p>\n<p><strong>12.30h<\/strong> Disparo de Arcabucer\u00eda en la explanada del Castillo.<\/p>\n<p><strong>19.00h<\/strong> Entrada de Bandas de m\u00fasica desde el Castillo hasta el Fort\u00ed.<\/p>\n<p><strong>20.00h<\/strong> Gran desfile de Gala de los Bandos Moro y Cristiano. Al finalizar el desfile Castillo de Fuegos Artificiales.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding=&#8221;25px||9px|||&#8221; _builder_version=&#8221;3.23.3&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.23.3&#8243;][et_pb_text _builder_version=&#8221;3.23.3&#8243;]<\/p>\n<p><a href=\"http:\/\/www.turismoteuladamoraira.com\/teumor\/uploaded\/2019\/MOROS%20Y%20CRISTIANOS%202019\/ESP_Programa%20Moros%20i%20Cristians%202019-2.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar<\/a> la Programaci\u00f3n.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding=&#8221;45px|||||&#8221; _builder_version=&#8221;3.23.3&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.23.3&#8243;][et_pb_text _builder_version=&#8221;3.23.3&#8243;]<\/p>\n<p style=\"text-align: center\"><strong>Inmobres tiene la casa de tus sue\u00f1os y disfruta de las maravillosas fiestas que te ofrece la Costa Blanca.<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/inmobres.es\/wp-content\/uploads\/2018\/04\/banner-02-inmobres-min.jpg&#8221; url=&#8221;https:\/\/www.inmobres.com\/es\/&#8221; url_new_window=&#8221;on&#8221; _builder_version=&#8221;3.23.3&#8243; width=&#8221;70%&#8221; width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No puedes faltar a esta tradicional fiesta de los Moros y Cristianos que se celebra del 7 al 16 de Junio 2019 en Moraira.<\/p>\n","protected":false},"author":3,"featured_media":3782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[18],"tags":[29,53,41,9,54,30],"class_list":["post-3773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-y-fiestas","tag-calp","tag-costa-blanca","tag-fiesta","tag-inmobres","tag-moraira","tag-moros-y-cristianos"],"_links":{"self":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts\/3773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/comments?post=3773"}],"version-history":[{"count":0,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts\/3773\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/media\/3782"}],"wp:attachment":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/media?parent=3773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/categories?post=3773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/tags?post=3773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}