{"id":14516,"date":"2025-10-07T11:13:01","date_gmt":"2025-10-07T09:13:01","guid":{"rendered":"https:\/\/inmobres.es\/?p=14516"},"modified":"2025-10-17T12:16:37","modified_gmt":"2025-10-17T10:16:37","slug":"programacion-de-moros-y-cristianos-calpe-2025","status":"publish","type":"post","link":"https:\/\/inmobres.es\/en\/programacion-de-moros-y-cristianos-calpe-2025\/","title":{"rendered":"\ud83c\udf89 Programaci\u00f3n de Moros y Cristianos Calpe 2025"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/inmobres.es\/en\/programacion-de-moros-y-cristianos-calpe-2025\/#Programacion_de_Moros_y_Cristianos_Calpe_2025\" >Programaci\u00f3n de Moros y Cristianos Calpe 2025<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/inmobres.es\/en\/programacion-de-moros-y-cristianos-calpe-2025\/#%F0%9F%93%85_Jueves_16_de_octubre\" >\ud83d\udcc5 Jueves 16 de octubre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/inmobres.es\/en\/programacion-de-moros-y-cristianos-calpe-2025\/#%F0%9F%8E%BA_Viernes_17_de_octubre\" >\ud83c\udfba Viernes 17 de octubre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/inmobres.es\/en\/programacion-de-moros-y-cristianos-calpe-2025\/#%F0%9F%9B%A1%EF%B8%8F_Sabado_18_de_octubre\" >\ud83d\udee1\ufe0f S\u00e1bado 18 de octubre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/inmobres.es\/en\/programacion-de-moros-y-cristianos-calpe-2025\/#%E2%9A%94%EF%B8%8F_Domingo_19_de_octubre\" >\u2694\ufe0f Domingo 19 de octubre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/inmobres.es\/en\/programacion-de-moros-y-cristianos-calpe-2025\/#%F0%9F%8C%99_Lunes_20_de_octubre\" >\ud83c\udf19 Lunes 20 de octubre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/inmobres.es\/en\/programacion-de-moros-y-cristianos-calpe-2025\/#%F0%9F%92%A5_Martes_21_de_octubre\" >\ud83d\udca5 Martes 21 de octubre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/inmobres.es\/en\/programacion-de-moros-y-cristianos-calpe-2025\/#%F0%9F%99%8F_Miercoles_22_de_octubre\" >\ud83d\ude4f Mi\u00e9rcoles 22 de octubre<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/inmobres.es\/en\/programacion-de-moros-y-cristianos-calpe-2025\/#%E2%9C%A8_Vive_los_Moros_y_Cristianos_de_Calpe_2025\" >\u2728 Vive los Moros y Cristianos de Calpe 2025<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>Las <strong>Fiestas de Moros y Cristianos Calpe 2025<\/strong> llenar\u00e1n las calles de color, m\u00fasica y tradici\u00f3n del <strong>jueves 16 al mi\u00e9rcoles 22 de octubre<\/strong>. Durante una semana, calpinos y visitantes podr\u00e1n disfrutar de desfiles, batallas, m\u00fasica festera, pregones y espect\u00e1culos \u00fanicos que rinden homenaje al <strong>Sant\u00edssim Crist de la Suor<\/strong>, patr\u00f3n de la ciudad.<\/p>\n\n\n\n<p>A continuaci\u00f3n, te dejamos la programaci\u00f3n completa d\u00eda por d\u00eda para que no te pierdas ninguno de los actos m\u00e1s emblem\u00e1ticos.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"400\" height=\"535\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2025\/10\/Moros-y-Cristianos-Calpe-2025.jpg\" alt=\"Moros y Cristianos Calpe 2025\" class=\"wp-image-14517\" style=\"width:256px;height:auto\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2025\/10\/Moros-y-Cristianos-Calpe-2025.jpg 400w, https:\/\/inmobres.es\/wp-content\/uploads\/2025\/10\/Moros-y-Cristianos-Calpe-2025-150x200.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><figcaption class=\"wp-element-caption\">Moros y Cristianos Calpe 2025<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Programacion_de_Moros_y_Cristianos_Calpe_2025\"><\/span>Programaci\u00f3n de Moros y Cristianos Calpe 2025<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%F0%9F%93%85_Jueves_16_de_octubre\"><\/span>\ud83d\udcc5 <strong>Jueves 16 de octubre<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><strong>20:00 &#8211; 23:30 | Casa de la Cultura \u201cJaume Pastor i Fluix\u00e0\u201d, Av. Masnou, 1<\/strong><br>Presentaci\u00f3n del <strong>Libro de Fiestas<\/strong>, presentaci\u00f3n oficial de la <strong>Pregonera de las Fiestas de Moros y Cristianos 2025<\/strong> y, a continuaci\u00f3n, <strong>Concierto de M\u00fasica Festera<\/strong> en la <strong>Plaza Mayor<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%F0%9F%8E%BA_Viernes_17_de_octubre\"><\/span>\ud83c\udfba <strong>Viernes 17 de octubre<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><strong>13:00 &#8211; 14:00 | Aviso de inicio de fiestas<\/strong><br>Volteo de campanas y salvas de ordenanza.<\/p>\n\n\n\n<p><strong>18:30 &#8211; 19:30 | Entrada de bandas<\/strong><br>Desde <strong>Plaza Col\u00f3n hasta Plaza Mosquit<\/strong>.<\/p>\n\n\n\n<p><strong>19:30 &#8211; 20:00 | Pasacalle Filaes Moras y Cristianas<\/strong><br>Recorrido hasta la <strong>Plaza Mayor<\/strong>.<\/p>\n\n\n\n<p><strong>20:00 &#8211; 21:30 | Preg\u00f3n e Izada de Estandartes<\/strong><br>En la <strong>Plaza Mayor<\/strong>, seguido de una <strong>ofrenda de cirios<\/strong> al <strong>Sant\u00edssim Crist de la Suor<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%F0%9F%9B%A1%EF%B8%8F_Sabado_18_de_octubre\"><\/span>\ud83d\udee1\ufe0f <strong>S\u00e1bado 18 de octubre<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><strong>00:30 &#8211; 01:00 | Pasacalle nocturno<\/strong><br>Todas las charangas tocar\u00e1n juntas una marcha mora y una cristiana en la <strong>Plaza del Mosquit<\/strong>.<\/p>\n\n\n\n<p><strong>01:00 &#8211; 02:30 | Baile Capitan\u00eda Cristiana \u2013 Fil\u00e1 Moz\u00e1rabes<\/strong><\/p>\n\n\n\n<p><strong>09:30 &#8211; 12:00 | Diana y almuerzo festero<\/strong><\/p>\n\n\n\n<p><strong>18:30 &#8211; 23:30 | Entrada Cristiana y Mora<\/strong><br>Uno de los momentos m\u00e1s esperados de las fiestas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E2%9A%94%EF%B8%8F_Domingo_19_de_octubre\"><\/span>\u2694\ufe0f <strong>Domingo 19 de octubre<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><strong>10:15 &#8211; 10:45 | Concentraci\u00f3n Bando Cristiano<\/strong><br>En la <strong>Plaza del Mosquit<\/strong>.<\/p>\n\n\n\n<p><strong>10:45 &#8211; 12:30 | Desembarco y Primera Batalla<\/strong><br>En la <strong>Playa del Arenal-Bol<\/strong>, con recreaci\u00f3n hist\u00f3rica.<\/p>\n\n\n\n<p><strong>19:00 &#8211; 23:30 | Desfile Infantil<\/strong><br>Los m\u00e1s peque\u00f1os tambi\u00e9n toman las calles de Calpe con sus trajes festeros.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%99_Lunes_20_de_octubre\"><\/span>\ud83c\udf19 <strong>Lunes 20 de octubre<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><strong>01:00 &#8211; 03:00 | Baile Capitan\u00eda Mora \u2013 Fil\u00e1 Tuareg<\/strong><\/p>\n\n\n\n<p><strong>23:00 &#8211; 23:30 | Correfocs<\/strong><br>Un espect\u00e1culo de fuego, luz y m\u00fasica por las calles del centro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%F0%9F%92%A5_Martes_21_de_octubre\"><\/span>\ud83d\udca5 <strong>Martes 21 de octubre<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><strong>20:30 &#8211; 23:30 | Plaza Mayor<\/strong><br>Recreaci\u00f3n del <strong>Parlamento y Segunda Batalla<\/strong>, conocida como el <strong>\u201cMiracle\u201d<\/strong>, uno de los actos m\u00e1s simb\u00f3licos de la fiesta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%F0%9F%99%8F_Miercoles_22_de_octubre\"><\/span>\ud83d\ude4f <strong>Mi\u00e9rcoles 22 de octubre<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><strong>01:00 &#8211; 03:00 | Baile Abanderada de la Asociaci\u00f3n \u2013 Fil\u00e1 Berberiscos<\/strong><\/p>\n\n\n\n<p><strong>11:15 &#8211; 12:00 | Concentraci\u00f3n de Festeros en Plaza del Mosquit<\/strong><br><strong>12:00 &#8211; 13:30 | Misa Solemne y Masclet\u00e1<\/strong><br>En honor al <strong>Sant\u00edssim Crist de la Suor<\/strong>, seguida de una <strong>gran masclet\u00e1<\/strong>.<\/p>\n\n\n\n<p><strong>19:30 &#8211; 21:30 | Solemne Procesi\u00f3n y Masclet\u00e1 Nocturna<\/strong><br>Tras la procesi\u00f3n, pasacalle hacia la <strong>masclet\u00e1 nocturna<\/strong> que pondr\u00e1 fin a las fiestas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E2%9C%A8_Vive_los_Moros_y_Cristianos_de_Calpe_2025\"><\/span>\u2728 Vive los Moros y Cristianos de Calpe 2025<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Del <strong>16 al 22 de octubre<\/strong>, Calpe se transforma en un escenario festivo donde la historia, la m\u00fasica y la devoci\u00f3n se unen. Si nunca has vivido los <strong>Moros y Cristianos de Calpe<\/strong>, este a\u00f1o es la ocasi\u00f3n perfecta para hacerlo.<br>Disfruta de los desfiles, el ambiente y la hospitalidad de una de las fiestas m\u00e1s queridas de la Costa Blanca.<\/p>\n\n\n\n<p>En\u00a0<strong><a href=\"https:\/\/www.inmobres.com\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Inmobres<\/a> te ayudamos a encontrar la casa de tus sue\u00f1os, junto al Mediterr\u00e1neo.<\/strong><\/p>\n\n\n\n<p><a href=\"tel:+34656633190\" target=\"_blank\" rel=\"noreferrer noopener\">Ll\u00e1manos<\/a>&nbsp; o escr\u00edbenos un&nbsp;<a href=\"mailto:info@inmobres.com\">correo electr\u00f3nico<\/a>. Tambi\u00e9n puedes venir a vernos a&nbsp;<a href=\"https:\/\/g.page\/InmobresCalpe?share\" target=\"_blank\" rel=\"noreferrer noopener\">nuestra oficina<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Fiestas de Moros y Cristianos Calpe 2025 llenar\u00e1n las calles de color, m\u00fasica y tradici\u00f3n del jueves 16 al mi\u00e9rcoles 22 de octubre.<\/p>\n","protected":false},"author":6,"featured_media":14517,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[18],"tags":[29,32,53,14,9,1683,1682],"class_list":["post-14516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-y-fiestas","tag-calp","tag-calpe","tag-costa-blanca","tag-inmobiliaria","tag-inmobres","tag-moros-y-cristianos-calpe-2025","tag-programacion-de-moros-y-cristianos-calpe-2025"],"_links":{"self":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts\/14516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/comments?post=14516"}],"version-history":[{"count":4,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts\/14516\/revisions"}],"predecessor-version":[{"id":14534,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts\/14516\/revisions\/14534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/media\/14517"}],"wp:attachment":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/media?parent=14516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/categories?post=14516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/tags?post=14516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}