{"id":14270,"date":"2025-04-23T14:09:06","date_gmt":"2025-04-23T12:09:06","guid":{"rendered":"https:\/\/inmobres.es\/?p=14270"},"modified":"2025-04-23T14:09:08","modified_gmt":"2025-04-23T12:09:08","slug":"programacion-mercado-medieval-calpe-2025","status":"publish","type":"post","link":"https:\/\/inmobres.es\/en\/programacion-mercado-medieval-calpe-2025\/","title":{"rendered":"Programaci\u00f3n Mercado Medieval Calpe 2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Aqu\u00ed te dejamos la programaci\u00f3n del <strong>Mercado Medieval Calpe<\/strong> <strong>2025<\/strong>, ven y disfruta de numerosos festejos. Desde el viernes 25 al 27 de abril.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Programaci\u00f3n Mercado Medieval Calpe 2025<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Viernes 25<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">18:00h &#8211; Inauguraci\u00f3n del mercado medieval con m\u00fasicos de ambientaci\u00f3n medieval y bailarina<br>18:00h &#8211; Cuentacuentos<br>18:00 a 21:00h &#8211; Taller infantil de pintura de cofres y m\u00e1scaras<br>19:30h &#8211; Cuentacuentos<br>20:00h &#8211; Grupo musical con bailarina y espect\u00e1culo de fuego &#8220;\u00e1nimas de la noche&#8221; con Vendaval Folk<br>21:00h &#8211; Grupo musical con bailarina &#8220;los lobos salvajes&#8221; con Vendaval Folk<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">S\u00e1bado 26<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">11:00h &#8211; Apertura del mercado<br>11:00 a 13:30h &#8211; Taller infantil de pintura de cofres y m\u00e1scaras<br>12:00h &#8211; Grupo musical con bailarina llenan el mercado de melod\u00edas con Vendaval Folk<br>12:00h &#8211; Cuentacuentos<br>13:00h &#8211; Grupo musical con bailarina llenan el mercado de melod\u00edas con Vendaval Folk<br>13:15h &#8211; Cuentacuentos<br>18:00h &#8211; Cuentacuentos<br>18:00 a 21:00h &#8211; Taller infantil de pinturas de cofres y m\u00e1scaras<br>18:30h &#8211; Grupo musical con bailarina llenan el mercado de melod\u00edas con Vendaval Folk<br>19:30h &#8211; Cuentacuentos<br>20:00h &#8211; Grupo musical con bailarina y espect\u00e1culo de fuego &#8220;\u00e1nimas de la noche&#8221; con Vendaval Folk<br>21:00h &#8211; Grupo musical con bailarina &#8220;los lobos salvajes&#8221; con Vendaval Folk<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2025\/04\/491914204_1104480908387361_717893738013975045_n.jpg\"><img decoding=\"async\" width=\"1131\" height=\"1600\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2025\/04\/491914204_1104480908387361_717893738013975045_n.jpg\" alt=\"Programaci\u00f3n Mercado Medieval Calpe 2025\" class=\"wp-image-14271\" style=\"width:324px;height:auto\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2025\/04\/491914204_1104480908387361_717893738013975045_n.jpg 1131w, https:\/\/inmobres.es\/wp-content\/uploads\/2025\/04\/491914204_1104480908387361_717893738013975045_n-980x1386.jpg 980w, https:\/\/inmobres.es\/wp-content\/uploads\/2025\/04\/491914204_1104480908387361_717893738013975045_n-480x679.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1131px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Programaci\u00f3n Mercado Medieval Calpe 2025<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Domingo 27<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">11:00h &#8211; Apertura del mercado<br>11:00 a 13:30h &#8211; Taller infantil de pintura de cofres y m\u00e1scaras<br>12:00h &#8211; Grupo musical con bailarina llenan el mercado de melod\u00edas con Vendaval Folk<br>12:00h &#8211; Cuentacuentos<br>13:00h &#8211; Grupo musical con bailarina llenan el mercado de melod\u00edas con Vendaval Folk<br>13:15h &#8211; Cuentacuentos<br>18:00h &#8211; Cuentacuentos<br>18:00 a 21:00h &#8211; Taller infantil de pintura de cofres y m\u00e1scaras<br>18:30h &#8211; Grupo musical con bailarina llenan el mercado de melod\u00edas con Vendaval Folk<br>19:30h &#8211; Cuentacuentos<br>20:00h &#8211; Grupo musical con bailarina y espect\u00e1culo de fuego &#8220;\u00e1nimas de la noche&#8221; con Vendaval Folk<br>21:00h &#8211; Grupo musical con bailarina &#8220;los lobos salvajes&#8221; con Vendaval Folk<br>22:00h &#8211; Cierre del mercado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En&nbsp;<strong>Inmobres te ayudamos a encontrar la casa de tus sue\u00f1os, junto al Mediterr\u00e1neo.<\/strong><br>Disfruta todos los a\u00f1os del <a href=\"https:\/\/www.calpe.es\/es\/evento\/mercado-medieval-abril-calpe\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">mercado medieval de Calpe<\/a>&nbsp;y el resto de fiestas de la Costa Blanca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"tel:+34656633190\" target=\"_blank\" rel=\"noreferrer noopener\">Ll\u00e1manos<\/a>&nbsp; o escr\u00edbenos un&nbsp;<a href=\"mailto:info@inmobres.com\">correo electr\u00f3nico<\/a>. Tambi\u00e9n puedes venir a vernos a&nbsp;<a href=\"https:\/\/g.page\/InmobresCalpe?share\" target=\"_blank\" rel=\"noreferrer noopener\">nuestra oficina<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aqu\u00ed te dejamos la programaci\u00f3n del Mercado Medieval Calpe 2025, ven y disfruta de numerosos festejos. Desde el viernes 25 al 27 de abril.<\/p>\n","protected":false},"author":3,"featured_media":14275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[1673],"tags":[29,32,53,14,9,1656,1657],"class_list":["post-14270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veranstaltungen-und-feste","tag-calp","tag-calpe","tag-costa-blanca","tag-inmobiliaria","tag-inmobres","tag-mercado-medieval-calpe-2025","tag-programacion-mercado-medieval-calpe-2025"],"_links":{"self":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts\/14270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/comments?post=14270"}],"version-history":[{"count":4,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts\/14270\/revisions"}],"predecessor-version":[{"id":14282,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/posts\/14270\/revisions\/14282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/media\/14275"}],"wp:attachment":[{"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/media?parent=14270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/categories?post=14270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inmobres.es\/en\/wp-json\/wp\/v2\/tags?post=14270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}