{"id":6243,"date":"2022-03-15T20:25:00","date_gmt":"2022-03-15T19:25:00","guid":{"rendered":"https:\/\/inmobres.es\/?p=6243"},"modified":"2022-03-10T12:35:08","modified_gmt":"2022-03-10T11:35:08","slug":"programacion-de-fallas-2022-en-calpe","status":"publish","type":"post","link":"https:\/\/inmobres.es\/de\/programacion-de-fallas-2022-en-calpe\/","title":{"rendered":"Programaci\u00f3n de Fallas 2022 en Calpe"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/inmobres.es\/de\/programacion-de-fallas-2022-en-calpe\/#Programacion_de_Fallas_2022_en_Calpe\" >Programaci\u00f3n de Fallas 2022 en Calpe<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/inmobres.es\/de\/programacion-de-fallas-2022-en-calpe\/#Jueves_17\" >Jueves 17<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/inmobres.es\/de\/programacion-de-fallas-2022-en-calpe\/#Viernes_18\" >Viernes 18<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/inmobres.es\/de\/programacion-de-fallas-2022-en-calpe\/#Sabado_19\" >S\u00e1bado 19<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed te dejamos la\u00a0<strong>Programaci\u00f3n de las Fallas 2022<\/strong>\u00a0en Calpe, se celebra\u00a0<strong>del 17 de marzo al 19 de marzo<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Programacion_de_Fallas_2022_en_Calpe\"><\/span>Programaci\u00f3n de Fallas 2022 en Calpe<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Comisi\u00f3n Fallera se reserva el derecho a modificar este programa.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Jueves_17\"><\/span>Jueves 17<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>18:30h<\/strong> &#8222;Plant\u00e0&#8220; Falla Calp Vell (Plaza Mayor).<br><strong>19:00h<\/strong> &#8222;Xocolat\u00e0&#8220; popular con churros (Plaza Mayor).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Viernes_18\"><\/span>Viernes 18<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>14:00h<\/strong> Paella popular (Plaza Mayor).<br><strong>18:00h<\/strong> Castillos hinchables y juegos infantiles (Plaza Mayor).<br><strong>23:00h<\/strong> DJ en directo (Plaza Mayor).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Sabado_19\"><\/span>S\u00e1bado 19<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>11:30h<\/strong> Recogida de autoridades y Fallera Mayor.<br><strong>12:30h<\/strong> Misa y ofrenda (Parroquia Virgen de las Nieves).<br><strong>13:30h<\/strong> &#8222;Masclet\u00e0&#8220; pirotecnia Redov\u00e1n (Plaza Mayor).<br><strong>18:00h<\/strong> Castillos hinchables y juegos infantiles (Plaza Mayor).<br><strong>23:00h<\/strong> &#8222;Crem\u00e0&#8220; de la Falla en la Plaza Mayor.<br><strong>23:30h<\/strong> DJ en directo (Plaza Mayor).<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/Portada.jpg\"><img decoding=\"async\" width=\"910\" height=\"1276\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/Portada.jpg\" alt=\"Programaci\u00f3n de Fallas 2022 en Calpe\" class=\"wp-image-6244\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/Portada.jpg 910w, https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/Portada-480x673.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 910px, 100vw\" \/><\/a><figcaption>Programaci\u00f3n de Fallas 2022 en Calpe<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/Programacion.jpg\"><img decoding=\"async\" width=\"910\" height=\"1276\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/Programacion.jpg\" alt=\"Programaci\u00f3n\" class=\"wp-image-6245\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/Programacion.jpg 910w, https:\/\/inmobres.es\/wp-content\/uploads\/2022\/03\/Programacion-480x673.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 910px, 100vw\" \/><\/a><figcaption>Programaci\u00f3n<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En\u00a0<strong>Inmobres te ayuda a encontrar la casa de tus sue\u00f1os, junto al Mediterr\u00e1neo.<\/strong> Ven y disfruta cada a\u00f1o de las\u00a0<strong>Fallas de Calpe<\/strong>\u00a0y nuestras maravillosas fiestas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"tel:+34656633190\" target=\"_blank\">Ll\u00e1manos<\/a>&nbsp; o escribenos un&nbsp;<a href=\"mailto:info@inmobres.com\">correo electr\u00f3nico<\/a>. Tambi\u00e9n puedes venir a vernos a&nbsp;<a href=\"https:\/\/g.page\/InmobresCalpe?share\" target=\"_blank\" rel=\"noreferrer noopener\">nuestra oficina<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aqu\u00ed te dejamos la\u00a0Programaci\u00f3n de las Fallas 2022\u00a0en Calpe, se celebra\u00a0del 17 al 19 de marzo. Ven y disfruta cada a\u00f1o de las\u00a0Fallas de Calpe\u00a0y nuestras maravillosas fiestas.<\/p>\n","protected":false},"author":3,"featured_media":6248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[18],"tags":[29,32,53,392,14,9,79],"class_list":["post-6243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-y-fiestas","tag-calp","tag-calpe","tag-costa-blanca","tag-fallas-2022","tag-inmobiliaria","tag-inmobres","tag-programacion"],"_links":{"self":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts\/6243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/comments?post=6243"}],"version-history":[{"count":1,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts\/6243\/revisions"}],"predecessor-version":[{"id":6247,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts\/6243\/revisions\/6247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/media\/6248"}],"wp:attachment":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/media?parent=6243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/categories?post=6243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/tags?post=6243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}