{"id":5040,"date":"2020-06-24T12:00:00","date_gmt":"2020-06-24T10:00:00","guid":{"rendered":"https:\/\/inmobres.es\/?p=5040"},"modified":"2023-03-07T17:40:55","modified_gmt":"2023-03-07T16:40:55","slug":"amplio-apartamento-de-3-habitaciones-en-calp","status":"publish","type":"post","link":"https:\/\/inmobres.es\/de\/amplio-apartamento-de-3-habitaciones-en-calp\/","title":{"rendered":"Amplio apartamento de 3 habitaciones en Calp"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/inmobres.es\/de\/amplio-apartamento-de-3-habitaciones-en-calp\/#%C2%A1VENDIDO\" >\u00a1VENDIDO!<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/inmobres.es\/de\/amplio-apartamento-de-3-habitaciones-en-calp\/#Precio\" >Precio<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/inmobres.es\/de\/amplio-apartamento-de-3-habitaciones-en-calp\/#Detalles\" >Detalles<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/inmobres.es\/de\/amplio-apartamento-de-3-habitaciones-en-calp\/#Caracteristicas\" >Caracter\u00edsticas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/inmobres.es\/de\/amplio-apartamento-de-3-habitaciones-en-calp\/#Descripcion_del_amplio_apartamento_de_3_habitaciones\" >Descripci\u00f3n del amplio apartamento de 3 habitaciones<\/a><\/li><\/ul><\/nav><\/div>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%A1VENDIDO\"><\/span><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">\u00a1VENDIDO!<\/mark><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Amplio apartamento de 164m\u00b2 y <strong>3 habitaciones<\/strong><\/strong> <strong>situado en Calp.<\/strong> Cerca de colegios, centros deportivos, de la estaci\u00f3n de autobuses y todos los dem\u00e1s servicios.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Precio\"><\/span>Precio<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Este amplio apartamento anteriormente tenia un precio de&nbsp;<strong>179.000\u20ac<\/strong>&nbsp;y ahora se ha reducido a&nbsp;<strong>159.000\u20ac<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ven y disfruta de las magn\u00edficas temperaturas que nos ofrece la Costa Blanca durante todo el a\u00f1o.<br><strong>\u00a1No puedes perder esta gran oferta!<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/25.jpg\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/25.jpg\" alt=\"Habitaci\u00f3n principal\" class=\"wp-image-5045\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/25.jpg 1200w, https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/25-980x653.jpg 980w, https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/25-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Habitaci\u00f3n principal<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Detalles\"><\/span>Detalles<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Poblaci\u00f3n:&nbsp;<\/strong>Calpe \/ Calp<\/li>\n\n\n\n<li><strong>Habitaciones:&nbsp;<\/strong>3<\/li>\n\n\n\n<li><strong>Ba\u00f1os:&nbsp;<\/strong>2<\/li>\n\n\n\n<li><strong>Superficie Construida:&nbsp;<\/strong>164 m\u00b2<\/li>\n\n\n\n<li><strong>Planta:&nbsp;<\/strong>6\u00ba<\/li>\n\n\n\n<li><strong>Referencia:<\/strong> 0241bres<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Caracteristicas\"><\/span>Caracter\u00edsticas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Cocina:&nbsp;<\/strong>Independiente y Equipada<\/li>\n\n\n\n<li><strong>Terraza:&nbsp;<\/strong>No Acristalada<\/li>\n\n\n\n<li><strong>Orientaci\u00f3n:&nbsp;<\/strong>Este<\/li>\n\n\n\n<li><strong>Vistas:&nbsp;<\/strong>Despejadas<\/li>\n\n\n\n<li><strong>Tipo de calefacci\u00f3n:&nbsp;<\/strong>A gas &#8211; Central<\/li>\n\n\n\n<li><strong>Calentador de agua:&nbsp;<\/strong>Gas butano &#8211; Individual<\/li>\n\n\n\n<li><strong>Amueblado<\/strong>, <strong>Puerta Blindada<\/strong>, <strong>Aire Acondicionado<\/strong>, <strong>Ascensor<\/strong>, <strong>Armarios empotrados<\/strong>, <strong>Doble acristalamiento<\/strong>, <strong>Ventanas<\/strong>, <strong>Trastero y<\/strong> <strong>Admite mascotas.<\/strong><\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/12.jpg\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/12.jpg\" alt=\"Cocina del amplio apartamento\" class=\"wp-image-5042\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/12.jpg 1200w, https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/12-980x653.jpg 980w, https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/12-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Cocina del amplio apartamento<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Descripcion_del_amplio_apartamento_de_3_habitaciones\"><\/span>Descripci\u00f3n del amplio apartamento de 3 habitaciones<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El apartamento se encuentra en un 6\u00ba piso con ascensor y se distribuye en amplio sal\u00f3n, cocina totalmente independiente y equipada, tres dormitorios y dos cuartos de ba\u00f1o completos, uno con hidromasaje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, el piso cuenta con balc\u00f3n, que aporta gran luminosidad a toda la estancia, terraza, para que disfrutes del buen tiempo, un patio con muchas posibilidades y armarios empotrados para aumentar la capacidad de almacenaje de tu hogar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con orientaci\u00f3n este, en esta casa disfrutar\u00e1s del sol por las ma\u00f1anas. La vivienda, est\u00e1 amueblada y en buen estado, lista para entrar a vivir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El inmueble es todo exterior y cuenta con trastero en el mismo piso con ventana, para que puedas aprovechar todo el espacio de la vivienda. Este piso est\u00e1 situado en una v\u00eda de f\u00e1cil acceso.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/23.jpg\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/23.jpg\" alt=\"Ba\u00f1o del apartamento\" class=\"wp-image-5043\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/23.jpg 1200w, https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/23-980x653.jpg 980w, https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/23-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Ba\u00f1o del apartamento<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/11.jpg\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/11.jpg\" alt=\"Vistas del Amplio Apartamento de 3 habitaciones\" class=\"wp-image-5046\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/11.jpg 1200w, https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/11-980x653.jpg 980w, https:\/\/inmobres.es\/wp-content\/uploads\/2020\/06\/11-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Vistas del Amplio Apartamento de 3 habitaciones<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a las calidades, cuenta con calefacci\u00f3n central a gas (contador individual), caja fuerte empotrada, aire acondicionado con bomba de calor, carpinter\u00eda exterior de aluminio, suelos de una imitaci\u00f3n a m\u00e1rmol de ven\u00eds y para que te sientas m\u00e1s seguro en tu hogar, la puerta principal es blindada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfNo es la propiedad que buscas? En nuestra secci\u00f3n de&nbsp;<a href=\"https:\/\/inmobres.es\/categorias\/promociones\/\">Promociones<\/a>&nbsp;encontrar\u00e1s muchas m\u00e1s ofertas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"tel:+34656633190\" target=\"_blank\">Ll\u00e1manos<\/a>&nbsp;para una visita o solicita&nbsp;<a href=\"mailto:info@inmobres.com\">m\u00e1s informaci\u00f3n por correo electr\u00f3nico<\/a>. Tambi\u00e9n puedes ver m\u00e1s fotos de esta propiedad visitando&nbsp;<a href=\"https:\/\/www.inmobres.com\/es\/apartamento-en-calpe-calp-calpe-con-ascensor-es651957.html\" target=\"_blank\" aria-label=\" (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"rank-math-link\">nuestra p\u00e1gina web<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amplio apartamento de 164m\u00b2 y 3 habitaciones situado en Calp. Cerca de colegios, centros deportivos, de la estaci\u00f3n de autobuses y todos los dem\u00e1s servicios.<\/p>\n","protected":false},"author":3,"featured_media":5041,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[542],"tags":[304,29,32,53,9],"class_list":["post-5040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert","tag-amplio-apartamento","tag-calp","tag-calpe","tag-costa-blanca","tag-inmobres"],"_links":{"self":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts\/5040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/comments?post=5040"}],"version-history":[{"count":1,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts\/5040\/revisions"}],"predecessor-version":[{"id":10620,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts\/5040\/revisions\/10620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/media\/5041"}],"wp:attachment":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/media?parent=5040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/categories?post=5040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/tags?post=5040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}