{"id":3996,"date":"2019-07-31T12:30:49","date_gmt":"2019-07-31T10:30:49","guid":{"rendered":"https:\/\/inmobres.es\/?p=3996"},"modified":"2020-09-02T10:50:24","modified_gmt":"2020-09-02T08:50:24","slug":"albondigas-de-cordero-con-salsa-de-yogur","status":"publish","type":"post","link":"https:\/\/inmobres.es\/de\/albondigas-de-cordero-con-salsa-de-yogur\/","title":{"rendered":"Alb\u00f3ndigas de cordero con salsa de yogur"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/inmobres.es\/de\/albondigas-de-cordero-con-salsa-de-yogur\/#Ingredientes_para_4_personas\" >Ingredientes para 4 personas<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/inmobres.es\/de\/albondigas-de-cordero-con-salsa-de-yogur\/#Ingredientes_para_las_albondigas_de_cordero\" >Ingredientes para las alb\u00f3ndigas de cordero<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/inmobres.es\/de\/albondigas-de-cordero-con-salsa-de-yogur\/#Ingredientes_para_la_salsa_de_yogur\" >Ingredientes para la salsa de yogur<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/inmobres.es\/de\/albondigas-de-cordero-con-salsa-de-yogur\/#Elaboracion_para_4_personas\" >Elaboraci\u00f3n para 4 personas<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/inmobres.es\/de\/albondigas-de-cordero-con-salsa-de-yogur\/#Elaboracion_de_las_albondigas_de_cordero_con_salsa_de_yogur\" >Elaboraci\u00f3n de las alb\u00f3ndigas de cordero con salsa de yogur<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/inmobres.es\/de\/albondigas-de-cordero-con-salsa-de-yogur\/#Elaboracion_de_la_salsa_de_yogur\" >Elaboraci\u00f3n de la salsa de yogur<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;3.26.5&#8243;][et_pb_row _builder_version=&#8220;3.26.5&#8243;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.26.5&#8243;][et_pb_text _builder_version=&#8220;3.27.4&#8243;]<\/p>\n<p>Exquisita receta de <strong>alb\u00f3ndigas de cordero con salsa de yogur<\/strong>. Prepara este delicioso entrante y sorprende a todos tus comensales.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.26.5&#8243;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.26.5&#8243;][et_pb_text _builder_version=&#8220;3.27.4&#8243;]<\/p>\n<p>T\u00f3malas como quieras, ya que <strong>est\u00e1n igual de buenas calientes y fr\u00edas<\/strong>.<\/p>\n<p>Recuerda, no las hagas muy grandes. As\u00ed, cada comensal puede coger una alb\u00f3ndiga y mojarla en la salsa de yogur.<\/p>\n<p>Aunque esta receta es de cordero, <strong>tambi\u00e9n est\u00e1n buena con otras carnes<\/strong>, como ternera o mezcla de carnes.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;3.27.4&#8243; custom_margin=&#8220;||-2px|||&#8220;]<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Ingredientes_para_4_personas\"><\/span>Ingredientes para 4 personas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;3.26.5&#8243; custom_padding=&#8220;0px|||||&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;3.26.5&#8243;][et_pb_text _builder_version=&#8220;3.27.4&#8243;]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Ingredientes_para_las_albondigas_de_cordero\"><\/span>Ingredientes para las alb\u00f3ndigas de cordero<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>600 gr de carne de cordero picada<\/li>\n<li>1 huevo grande<\/li>\n<li>100 gr de miga de pan<\/li>\n<li>4 cucharadas de perejil picado<\/li>\n<li>Una rama de menta fresca<\/li>\n<li>2 dientes de ajo<\/li>\n<li>1 cucharada de comino molido<\/li>\n<li>Sal y pimienta<\/li>\n<li>Aceite de oliva<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;3.26.5&#8243;][et_pb_text _builder_version=&#8220;3.27.4&#8243;]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Ingredientes_para_la_salsa_de_yogur\"><\/span>Ingredientes para la salsa de yogur<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>2 yogures naturales sin az\u00facar (mejor tipo griego)<\/li>\n<li>1 diente de ajo peque\u00f1o triturado o una cucharadita de ajo en polvo<\/li>\n<li>Unas 12 hojas de menta picada<\/li>\n<li>Un chorro peque\u00f1o de zumo de lim\u00f3n<\/li>\n<li>Sal<\/li>\n<li>2 cucharadas de aceite de oliva<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.26.5&#8243; custom_padding=&#8220;4px|||||&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.26.5&#8243;][et_pb_text _builder_version=&#8220;3.27.4&#8243; custom_margin=&#8220;||-2px|||&#8220;]<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Elaboracion_para_4_personas\"><\/span>Elaboraci\u00f3n para 4 personas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;3_5,2_5&#8243; _builder_version=&#8220;3.26.5&#8243; custom_padding=&#8220;0px|||||&#8220;][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;3.26.5&#8243;][et_pb_text _builder_version=&#8220;3.27.4&#8243;]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Elaboracion_de_las_albondigas_de_cordero_con_salsa_de_yogur\"><\/span>Elaboraci\u00f3n de las alb\u00f3ndigas de cordero con salsa de yogur<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ol>\n<li>Pon en un cuenco la\u00a0carne picada, la miga de pan mojada en leche y escurrida, el ajo triturado (o ajo en polvo), el huevo, el perejil y la menta muy bien picados, el comino, la sal y la pimienta blanca. Mezclar todo bien hasta que quede una masa compacta.<\/li>\n<li>Forma las\u00a0alb\u00f3ndigas\u00a0no muy grandes, enhar\u00ednalas y reh\u00f3galas en un poco de aceite hasta que est\u00e9n bien doradas por todos lados. Sirve las alb\u00f3ndigas calientes acompa\u00f1adas con la salsa fr\u00eda y con unos palitos de aperitivo para poder pincharlas y mojar en la salsa.<\/li>\n<li>Si las quieres preparar con antelaci\u00f3n s\u00f3lo tienes que darles al final un golpe de calor en el\u00a0microondas.<\/li>\n<\/ol>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;3.27.4&#8243;]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Elaboracion_de_la_salsa_de_yogur\"><\/span>Elaboraci\u00f3n de la salsa de yogur<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Mezclamos muy bien todos los ingredientes hasta que quede una mezcla bien integrada y dejamos reposar unos 10 minutos.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;3.26.5&#8243;][et_pb_text _builder_version=&#8220;3.27.4&#8243;]<div id=\"attachment_4010\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-4010\" class=\"wp-image-4010 size-full\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/07\/inmobres-albondigas-de-cordero-en-salsa-de-yogur-pasos.jpg\" alt=\"Pasos para elaborar alb\u00f3ndigas de cordero con salsa de yogur.\" width=\"600\" height=\"600\" title=\"\" srcset=\"https:\/\/inmobres.es\/wp-content\/uploads\/2022\/07\/inmobres-albondigas-de-cordero-en-salsa-de-yogur-pasos.jpg 600w, https:\/\/inmobres.es\/wp-content\/uploads\/2022\/07\/inmobres-albondigas-de-cordero-en-salsa-de-yogur-pasos-150x150.jpg 150w, https:\/\/inmobres.es\/wp-content\/uploads\/2022\/07\/inmobres-albondigas-de-cordero-en-salsa-de-yogur-pasos-300x300.jpg 300w, https:\/\/inmobres.es\/wp-content\/uploads\/2022\/07\/inmobres-albondigas-de-cordero-en-salsa-de-yogur-pasos-560x560.jpg 560w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-4010\" class=\"wp-caption-text\">Pasos para elaborar alb\u00f3ndigas de cordero con salsa de yogur.<\/p><\/div>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.26.5&#8243;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.26.5&#8243;][et_pb_text _builder_version=&#8220;4.6.0&#8243; hover_enabled=&#8220;0&#8243; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p>Si prefieres servirlas como plato, acompa\u00f1a las alb\u00f3ndigas con un arroz blanco.<\/p>\n<p>Tienes m\u00e1s recetas en nuestra secci\u00f3n de <a href=\"https:\/\/inmobres.es\/categorias\/gastronomia\/\">gastronom\u00eda mediterr\u00e1nea<\/a>.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;3.27.4&#8243;]<\/p>\n<p>Receta original extra\u00edda de\u00a0<a href=\"https:\/\/divinacocina.hola.com\/albondigas-de-cordero-con-salsa-de-yogur\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/divinacocina.hola.com<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; width_tablet=&#8220;100%&#8220; width_phone=&#8220;&#8220; width_last_edited=&#8220;on|tablet&#8220; max_width=&#8220;80%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;&#8220; max_width_last_edited=&#8220;on|phone&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;3.27.4&#8243;]<\/p>\n<h4 style=\"text-align: center;\">Este sabroso plato lo encontrar\u00e1s en muchos restaurantes de la Costa Blanca.<\/h4>\n<h4 style=\"text-align: center;\">Ven a vivir al Mediterr\u00e1neo junto a nosotros y disfruta de la mejor gastronom\u00eda.<\/h4>\n<p>[\/et_pb_text][et_pb_image src=&#8220;https:\/\/inmobres.es\/wp-content\/uploads\/2019\/06\/Inmobres-03-1116_11522339055.jpg&#8220; url=&#8220;https:\/\/www.inmobres.com\/es&#8220; url_new_window=&#8220;on&#8220; align=&#8220;center&#8220; _builder_version=&#8220;3.26.5&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Exquisita receta de alb\u00f3ndigas de cordero con salsa de yogur. Prepara este delicioso entrante y sorprende a todos tus comensales.<\/p>\n","protected":false},"author":3,"featured_media":4011,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[19],"tags":[29,53,39,9,95],"class_list":["post-3996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gastronomia","tag-calp","tag-costa-blanca","tag-gastronomia","tag-inmobres","tag-recetas"],"_links":{"self":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts\/3996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/comments?post=3996"}],"version-history":[{"count":0,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts\/3996\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/media\/4011"}],"wp:attachment":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/media?parent=3996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/categories?post=3996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/tags?post=3996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}