{"id":11428,"date":"2023-06-21T12:00:00","date_gmt":"2023-06-21T10:00:00","guid":{"rendered":"https:\/\/inmobres.es\/?p=11428"},"modified":"2023-06-09T16:45:12","modified_gmt":"2023-06-09T14:45:12","slug":"programacion-de-los-toros-en-la-cometa-2023","status":"publish","type":"post","link":"https:\/\/inmobres.es\/de\/programacion-de-los-toros-en-la-cometa-2023\/","title":{"rendered":"Programaci\u00f3n de los Toros en la Cometa 2023"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/inmobres.es\/de\/programacion-de-los-toros-en-la-cometa-2023\/#Programacion_de_los_Toros_en_la_Cometa_2023\" >Programaci\u00f3n de los Toros en la Cometa 2023<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/inmobres.es\/de\/programacion-de-los-toros-en-la-cometa-2023\/#Sabado_24\" >S\u00e1bado 24<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/inmobres.es\/de\/programacion-de-los-toros-en-la-cometa-2023\/#Domingo_25\" >Domingo 25<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<p class=\"wp-block-paragraph\">Inmobres te trae la programaci\u00f3n de&nbsp;los&nbsp;<strong>Toros en la Cometa 2023 en Calp<\/strong>. Consulta los actos y fiestas que se celebrar\u00e1n del 24 al 25 de junio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Programacion_de_los_Toros_en_la_Cometa_2023\"><\/span>Programaci\u00f3n de los Toros en la Cometa 2023<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Sabado_24\"><\/span>S\u00e1bado 24<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>18:00h <\/strong>Apertura del Bar con precios populares y juegos para los m\u00e1s peque\u00f1os.<br><strong>19:30h <\/strong>Suelta de vacas.<br><strong>23:30h<\/strong> Suelta de vacas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Domingo_25\"><\/span>Domingo 25<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>09:30h <\/strong>Almuerzo popular.<br><strong>11:30h<\/strong> Suelta de vacas.<br><strong>17:30h <\/strong>Fiesta de la espuma y tardeo.<br><strong>19:30h<\/strong> Suelta de vacas.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/inmobres.es\/wp-content\/uploads\/2023\/06\/352787966_1015065216469407_1836509107570039682_n.jpg\"><img decoding=\"async\" src=\"https:\/\/inmobres.es\/wp-content\/uploads\/2023\/06\/352787966_1015065216469407_1836509107570039682_n.jpg\" alt=\"Programaci\u00f3n de los Toros en la Cometa 2023\" class=\"wp-image-11429\" width=\"366\" height=\"518\" title=\"\"><\/a><figcaption class=\"wp-element-caption\">Programaci\u00f3n de los Toros en la Cometa 2023<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En&nbsp;<strong>Inmobres te ayuda a encontrar la casa de tus sue\u00f1os, junto al Mediterr\u00e1neo.<\/strong><br>Disfruta todos los a\u00f1os de la fiesta de&nbsp;los&nbsp;<strong>Toros en la Cometa de Calpe&nbsp;<\/strong>y el resto de fiestas de la Costa Blanca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"tel:+34656633190\" target=\"_blank\" rel=\"noreferrer noopener\">Ll\u00e1manos<\/a>&nbsp; o escr\u00edbenos un&nbsp;<a href=\"mailto:info@inmobres.com\" target=\"_blank\" rel=\"noreferrer noopener\">correo electr\u00f3nico<\/a>. Tambi\u00e9n puedes venir a vernos a&nbsp;<a href=\"https:\/\/g.page\/InmobresCalpe?share\" target=\"_blank\" rel=\"noreferrer noopener\">nuestra oficina<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inmobres te trae la programaci\u00f3n de\u00a0los\u00a0Toros en la Cometa 2023 en Calp. Consulta los actos y fiestas que se celebrar\u00e1n del 24 al 25 de junio.<\/p>\n","protected":false},"author":3,"featured_media":11436,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[18],"tags":[29,32,53,14,9,1244,1245],"class_list":["post-11428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-y-fiestas","tag-calp","tag-calpe","tag-costa-blanca","tag-inmobiliaria","tag-inmobres","tag-programacion-toros","tag-toros-en-la-cometa-2023"],"_links":{"self":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts\/11428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/comments?post=11428"}],"version-history":[{"count":2,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts\/11428\/revisions"}],"predecessor-version":[{"id":11440,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/posts\/11428\/revisions\/11440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/media\/11436"}],"wp:attachment":[{"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/media?parent=11428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/categories?post=11428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inmobres.es\/de\/wp-json\/wp\/v2\/tags?post=11428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}